{"id":13968,"date":"2023-02-13T15:49:02","date_gmt":"2023-02-13T14:49:02","guid":{"rendered":"https:\/\/miramare.cultura.gov.it\/conferenza-stampa-di-presentazione-del-programma-di-iniziative-eventi-restauri-e-nuove-aperture-per-il-2023\/"},"modified":"2023-03-01T07:15:15","modified_gmt":"2023-03-01T06:15:15","slug":"conferenza-stampa-di-presentazione-del-programma-di-iniziative-eventi-restauri-e-nuove-aperture-per-il-2023","status":"publish","type":"post","link":"https:\/\/miramare.cultura.gov.it\/de\/conferenza-stampa-di-presentazione-del-programma-di-iniziative-eventi-restauri-e-nuove-aperture-per-il-2023\/","title":{"rendered":"Conferenza stampa di presentazione del programma di iniziative per il 2023"},"content":{"rendered":"<p>Si terr\u00e0 domani, <strong>marted\u00ec 14 febbraio alle ore 11.30,<\/strong> nella splendida Sala del Trono del Castello di Miramare, la conferenza stampa <strong>di presentazione del programma di iniziative, eventi, restauri e nuove aperture per il 2023.<\/strong> Il Direttore del Museo storico Andreina Contessa illustrer\u00e0 i progetti che saranno avviati nei prossimi mesi, le novit\u00e0 che riguardano le mostre e i protagonisti dei prossimi grandi incontri a Miramare e dar\u00e0 alcune notizie di rilievo sul Parco.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si terr\u00e0 domani, marted\u00ec 14 febbraio alle ore 11.30, nella splendida Sala del Trono del Castello di Miramare, la conferenza stampa di presentazione del programma di iniziative, eventi, restauri e nuove aperture per il 2023. Il Direttore del Museo storico Andreina Contessa illustrer\u00e0 i progetti che saranno avviati nei prossimi mesi, le novit\u00e0 che riguardano [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":13632,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[149,85],"tags":[150,151,152,153,154,155],"class_list":["post-13968","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-conferenze-de","category-news-de","tag-2023-de","tag-conferenza-stampa-de","tag-eventi-de","tag-miramare-de","tag-mostre-de","tag-programma-2023-de"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Conferenza stampa di presentazione del programma di iniziative per il 2023 | Museo Storico e Parco del Castello di Miramare<\/title>\n<meta name=\"description\" content=\"Conferenza stampa di presentazione del programma di iniziative per il 2023 | Museo Storico e Parco del Castello di Miramare | Un luogo nobile e romatico tra arte, natura e bellezza. | Si terr\u00e0 domani, marted\u00ec 14 febbraio alle ore 11.30, nella splendida Sala del Trono del Castello di Miramare, la conferenza stampa di presentazione del\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/miramare.cultura.gov.it\/de\/conferenza-stampa-di-presentazione-del-programma-di-iniziative-eventi-restauri-e-nuove-aperture-per-il-2023\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conferenza stampa di presentazione del programma di iniziative per il 2023 | Museo Storico e Parco del Castello di Miramare\" \/>\n<meta property=\"og:description\" content=\"Conferenza stampa di presentazione del programma di iniziative per il 2023 | Museo Storico e Parco del Castello di Miramare | Un luogo nobile e romatico tra arte, natura e bellezza. | Si terr\u00e0 domani, marted\u00ec 14 febbraio alle ore 11.30, nella splendida Sala del Trono del Castello di Miramare, la conferenza stampa di presentazione del\" \/>\n<meta property=\"og:url\" content=\"https:\/\/miramare.cultura.gov.it\/de\/conferenza-stampa-di-presentazione-del-programma-di-iniziative-eventi-restauri-e-nuove-aperture-per-il-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"Museo Storico e Parco del Castello di Miramare\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-13T14:49:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-01T06:15:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/miramare.cultura.gov.it\/wp-content\/uploads\/2023\/02\/IMG_20230214_120022_1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Irene Th\u00e9\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Irene Th\u00e9\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/de\\\/conferenza-stampa-di-presentazione-del-programma-di-iniziative-eventi-restauri-e-nuove-aperture-per-il-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/de\\\/conferenza-stampa-di-presentazione-del-programma-di-iniziative-eventi-restauri-e-nuove-aperture-per-il-2023\\\/\"},\"author\":{\"name\":\"Irene Th\u00e9\",\"@id\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/#\\\/schema\\\/person\\\/c108376ca4a46e1f0c1883ea8e0446c8\"},\"headline\":\"Conferenza stampa di presentazione del programma di iniziative per il 2023\",\"datePublished\":\"2023-02-13T14:49:02+00:00\",\"dateModified\":\"2023-03-01T06:15:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/de\\\/conferenza-stampa-di-presentazione-del-programma-di-iniziative-eventi-restauri-e-nuove-aperture-per-il-2023\\\/\"},\"wordCount\":81,\"image\":{\"@id\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/de\\\/conferenza-stampa-di-presentazione-del-programma-di-iniziative-eventi-restauri-e-nuove-aperture-per-il-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/IMG_20230214_120022_1-scaled.jpg\",\"keywords\":[\"2023\",\"conferenza stampa\",\"eventi\",\"Miramare\",\"mostre\",\"programma 2023\"],\"articleSection\":[\"Conferenze\",\"News\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/de\\\/conferenza-stampa-di-presentazione-del-programma-di-iniziative-eventi-restauri-e-nuove-aperture-per-il-2023\\\/\",\"url\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/de\\\/conferenza-stampa-di-presentazione-del-programma-di-iniziative-eventi-restauri-e-nuove-aperture-per-il-2023\\\/\",\"name\":\"Conferenza stampa di presentazione del programma di iniziative per il 2023 | Museo Storico e Parco del Castello di Miramare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/de\\\/conferenza-stampa-di-presentazione-del-programma-di-iniziative-eventi-restauri-e-nuove-aperture-per-il-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/de\\\/conferenza-stampa-di-presentazione-del-programma-di-iniziative-eventi-restauri-e-nuove-aperture-per-il-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/IMG_20230214_120022_1-scaled.jpg\",\"datePublished\":\"2023-02-13T14:49:02+00:00\",\"dateModified\":\"2023-03-01T06:15:15+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/#\\\/schema\\\/person\\\/c108376ca4a46e1f0c1883ea8e0446c8\"},\"description\":\"Conferenza stampa di presentazione del programma di iniziative per il 2023 | Museo Storico e Parco del Castello di Miramare | Un luogo nobile e romatico tra arte, natura e bellezza. | Si terr\u00e0 domani, marted\u00ec 14 febbraio alle ore 11.30, nella splendida Sala del Trono del Castello di Miramare, la conferenza stampa di presentazione del\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/de\\\/conferenza-stampa-di-presentazione-del-programma-di-iniziative-eventi-restauri-e-nuove-aperture-per-il-2023\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/miramare.cultura.gov.it\\\/de\\\/conferenza-stampa-di-presentazione-del-programma-di-iniziative-eventi-restauri-e-nuove-aperture-per-il-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/de\\\/conferenza-stampa-di-presentazione-del-programma-di-iniziative-eventi-restauri-e-nuove-aperture-per-il-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/IMG_20230214_120022_1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/IMG_20230214_120022_1-scaled.jpg\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/de\\\/conferenza-stampa-di-presentazione-del-programma-di-iniziative-eventi-restauri-e-nuove-aperture-per-il-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conferenza stampa di presentazione del programma di iniziative per il 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/#website\",\"url\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/\",\"name\":\"Museo Storico e Parco del Castello di Miramare\",\"description\":\"Un luogo nobile e romatico tra arte, natura e bellezza.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/#\\\/schema\\\/person\\\/c108376ca4a46e1f0c1883ea8e0446c8\",\"name\":\"Irene Th\u00e9\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5021168711c611352074e18f6b7606a9408d51ef9b6afff4154bea7af49fb80b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5021168711c611352074e18f6b7606a9408d51ef9b6afff4154bea7af49fb80b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5021168711c611352074e18f6b7606a9408d51ef9b6afff4154bea7af49fb80b?s=96&d=mm&r=g\",\"caption\":\"Irene Th\u00e9\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conferenza stampa di presentazione del programma di iniziative per il 2023 | Museo Storico e Parco del Castello di Miramare","description":"Conferenza stampa di presentazione del programma di iniziative per il 2023 | Museo Storico e Parco del Castello di Miramare | Un luogo nobile e romatico tra arte, natura e bellezza. | Si terr\u00e0 domani, marted\u00ec 14 febbraio alle ore 11.30, nella splendida Sala del Trono del Castello di Miramare, la conferenza stampa di presentazione del","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/miramare.cultura.gov.it\/de\/conferenza-stampa-di-presentazione-del-programma-di-iniziative-eventi-restauri-e-nuove-aperture-per-il-2023\/","og_locale":"de_DE","og_type":"article","og_title":"Conferenza stampa di presentazione del programma di iniziative per il 2023 | Museo Storico e Parco del Castello di Miramare","og_description":"Conferenza stampa di presentazione del programma di iniziative per il 2023 | Museo Storico e Parco del Castello di Miramare | Un luogo nobile e romatico tra arte, natura e bellezza. | Si terr\u00e0 domani, marted\u00ec 14 febbraio alle ore 11.30, nella splendida Sala del Trono del Castello di Miramare, la conferenza stampa di presentazione del","og_url":"https:\/\/miramare.cultura.gov.it\/de\/conferenza-stampa-di-presentazione-del-programma-di-iniziative-eventi-restauri-e-nuove-aperture-per-il-2023\/","og_site_name":"Museo Storico e Parco del Castello di Miramare","article_published_time":"2023-02-13T14:49:02+00:00","article_modified_time":"2023-03-01T06:15:15+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/miramare.cultura.gov.it\/wp-content\/uploads\/2023\/02\/IMG_20230214_120022_1-scaled.jpg","type":"image\/jpeg"}],"author":"Irene Th\u00e9","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Irene Th\u00e9","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/miramare.cultura.gov.it\/de\/conferenza-stampa-di-presentazione-del-programma-di-iniziative-eventi-restauri-e-nuove-aperture-per-il-2023\/#article","isPartOf":{"@id":"https:\/\/miramare.cultura.gov.it\/de\/conferenza-stampa-di-presentazione-del-programma-di-iniziative-eventi-restauri-e-nuove-aperture-per-il-2023\/"},"author":{"name":"Irene Th\u00e9","@id":"https:\/\/miramare.cultura.gov.it\/#\/schema\/person\/c108376ca4a46e1f0c1883ea8e0446c8"},"headline":"Conferenza stampa di presentazione del programma di iniziative per il 2023","datePublished":"2023-02-13T14:49:02+00:00","dateModified":"2023-03-01T06:15:15+00:00","mainEntityOfPage":{"@id":"https:\/\/miramare.cultura.gov.it\/de\/conferenza-stampa-di-presentazione-del-programma-di-iniziative-eventi-restauri-e-nuove-aperture-per-il-2023\/"},"wordCount":81,"image":{"@id":"https:\/\/miramare.cultura.gov.it\/de\/conferenza-stampa-di-presentazione-del-programma-di-iniziative-eventi-restauri-e-nuove-aperture-per-il-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/miramare.cultura.gov.it\/wp-content\/uploads\/2023\/02\/IMG_20230214_120022_1-scaled.jpg","keywords":["2023","conferenza stampa","eventi","Miramare","mostre","programma 2023"],"articleSection":["Conferenze","News"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/miramare.cultura.gov.it\/de\/conferenza-stampa-di-presentazione-del-programma-di-iniziative-eventi-restauri-e-nuove-aperture-per-il-2023\/","url":"https:\/\/miramare.cultura.gov.it\/de\/conferenza-stampa-di-presentazione-del-programma-di-iniziative-eventi-restauri-e-nuove-aperture-per-il-2023\/","name":"Conferenza stampa di presentazione del programma di iniziative per il 2023 | Museo Storico e Parco del Castello di Miramare","isPartOf":{"@id":"https:\/\/miramare.cultura.gov.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/miramare.cultura.gov.it\/de\/conferenza-stampa-di-presentazione-del-programma-di-iniziative-eventi-restauri-e-nuove-aperture-per-il-2023\/#primaryimage"},"image":{"@id":"https:\/\/miramare.cultura.gov.it\/de\/conferenza-stampa-di-presentazione-del-programma-di-iniziative-eventi-restauri-e-nuove-aperture-per-il-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/miramare.cultura.gov.it\/wp-content\/uploads\/2023\/02\/IMG_20230214_120022_1-scaled.jpg","datePublished":"2023-02-13T14:49:02+00:00","dateModified":"2023-03-01T06:15:15+00:00","author":{"@id":"https:\/\/miramare.cultura.gov.it\/#\/schema\/person\/c108376ca4a46e1f0c1883ea8e0446c8"},"description":"Conferenza stampa di presentazione del programma di iniziative per il 2023 | Museo Storico e Parco del Castello di Miramare | Un luogo nobile e romatico tra arte, natura e bellezza. | Si terr\u00e0 domani, marted\u00ec 14 febbraio alle ore 11.30, nella splendida Sala del Trono del Castello di Miramare, la conferenza stampa di presentazione del","breadcrumb":{"@id":"https:\/\/miramare.cultura.gov.it\/de\/conferenza-stampa-di-presentazione-del-programma-di-iniziative-eventi-restauri-e-nuove-aperture-per-il-2023\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/miramare.cultura.gov.it\/de\/conferenza-stampa-di-presentazione-del-programma-di-iniziative-eventi-restauri-e-nuove-aperture-per-il-2023\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/miramare.cultura.gov.it\/de\/conferenza-stampa-di-presentazione-del-programma-di-iniziative-eventi-restauri-e-nuove-aperture-per-il-2023\/#primaryimage","url":"https:\/\/miramare.cultura.gov.it\/wp-content\/uploads\/2023\/02\/IMG_20230214_120022_1-scaled.jpg","contentUrl":"https:\/\/miramare.cultura.gov.it\/wp-content\/uploads\/2023\/02\/IMG_20230214_120022_1-scaled.jpg","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/miramare.cultura.gov.it\/de\/conferenza-stampa-di-presentazione-del-programma-di-iniziative-eventi-restauri-e-nuove-aperture-per-il-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/miramare.cultura.gov.it\/de\/"},{"@type":"ListItem","position":2,"name":"Conferenza stampa di presentazione del programma di iniziative per il 2023"}]},{"@type":"WebSite","@id":"https:\/\/miramare.cultura.gov.it\/#website","url":"https:\/\/miramare.cultura.gov.it\/","name":"Museo Storico e Parco del Castello di Miramare","description":"Un luogo nobile e romatico tra arte, natura e bellezza.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/miramare.cultura.gov.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/miramare.cultura.gov.it\/#\/schema\/person\/c108376ca4a46e1f0c1883ea8e0446c8","name":"Irene Th\u00e9","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/5021168711c611352074e18f6b7606a9408d51ef9b6afff4154bea7af49fb80b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5021168711c611352074e18f6b7606a9408d51ef9b6afff4154bea7af49fb80b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5021168711c611352074e18f6b7606a9408d51ef9b6afff4154bea7af49fb80b?s=96&d=mm&r=g","caption":"Irene Th\u00e9"}}]}},"_links":{"self":[{"href":"https:\/\/miramare.cultura.gov.it\/de\/wp-json\/wp\/v2\/posts\/13968","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/miramare.cultura.gov.it\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/miramare.cultura.gov.it\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/miramare.cultura.gov.it\/de\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/miramare.cultura.gov.it\/de\/wp-json\/wp\/v2\/comments?post=13968"}],"version-history":[{"count":1,"href":"https:\/\/miramare.cultura.gov.it\/de\/wp-json\/wp\/v2\/posts\/13968\/revisions"}],"predecessor-version":[{"id":13970,"href":"https:\/\/miramare.cultura.gov.it\/de\/wp-json\/wp\/v2\/posts\/13968\/revisions\/13970"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/miramare.cultura.gov.it\/de\/wp-json\/wp\/v2\/media\/13632"}],"wp:attachment":[{"href":"https:\/\/miramare.cultura.gov.it\/de\/wp-json\/wp\/v2\/media?parent=13968"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/miramare.cultura.gov.it\/de\/wp-json\/wp\/v2\/categories?post=13968"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/miramare.cultura.gov.it\/de\/wp-json\/wp\/v2\/tags?post=13968"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}