{"id":9275,"date":"2021-03-29T00:00:00","date_gmt":"2021-03-28T22:00:00","guid":{"rendered":"https:\/\/miramare.cultura.gov.it\/miramare-paradiso-dantesco-2\/"},"modified":"2022-10-10T12:04:29","modified_gmt":"2022-10-10T10:04:29","slug":"miramare-paradiso-dantesco-2","status":"publish","type":"post","link":"https:\/\/miramare.cultura.gov.it\/de\/miramare-paradiso-dantesco-2\/","title":{"rendered":"Miramare, paradiso dantesco"},"content":{"rendered":"<p><iframe loading=\"lazy\" title=\"Vien dietro a me... - viaggio nella Divina Commedia attraverso i luoghi di Trieste\" src=\"https:\/\/player.vimeo.com\/video\/528439931?h=226b4efbec&amp;dnt=1&amp;app_id=122963\" width=\"1080\" height=\"608\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p>Il 25 marzo celebriamo il<span class=\"apple-converted-space\">\u00a0<\/span><strong>Danted\u00ec,<\/strong>\u00a0abbracciando e facendo risuonare dai luoghi di Miramare la bellezza universale delle parole del Sommo Poeta.<\/p>\n<p>Nella giornata che gli studiosi riconoscono come inizio del viaggio nell\u2019aldil\u00e0 della Divina Commedia, verr\u00e0 lanciato il video<span class=\"apple-converted-space\">\u00a0<\/span><strong>\u201cVien dietro a me&#8230; Viaggio nella Divina Commedia attraverso i luoghi di Trieste\u201d<\/strong>.<\/p>\n<p>La trascendenza del Paradiso e di quell\u2019\u00abamor che move il sole e l\u2019altre stelle\u00bb \u00e8 messa in scena proprio nei luoghi di Miramare dagli attori del<span class=\"apple-converted-space\">\u00a0<\/span><strong>Teatro Stabile Rossetti di Trieste<\/strong>, in uno spettacolo curato dal<span class=\"apple-converted-space\">\u00a0<\/span><strong>direttore<\/strong><span class=\"apple-converted-space\">\u00a0<\/span><strong>Paolo Valerio<\/strong><span class=\"apple-converted-space\">\u00a0<\/span>e con la sapiente conduzione del moderno Virgilio, il<span class=\"apple-converted-space\">\u00a0<\/span><strong>professor Fabio Romanini<\/strong>, dell\u2019Universit\u00e0 degli Studi di Trieste.<\/p>\n<p>Gli attori del Rossetti hanno scelto di<span class=\"apple-converted-space\">\u00a0<\/span><strong>recitare nel Parco di Miramare la prima parte del XXXI canto<\/strong><span class=\"apple-converted-space\">\u00a0<\/span>&#8211; sviluppato fra una dimensione di trascendenza e rimandi all\u2019idillio della natura &#8211;<span class=\"apple-converted-space\"><b>\u00a0<\/b><\/span><strong>e la parte finale del XXXIII canto<\/strong>.\u00a0 La prima parte del canto \u00e8 recitata da<span class=\"apple-converted-space\">\u00a0<\/span><strong>Jacopo Morra<\/strong><span class=\"apple-converted-space\">\u00a0<\/span>nel Gazebo adiacente il Castelletto, una vista ampia e vicina al cielo ma inserita nella natura.<span class=\"apple-converted-space\">\u00a0<\/span><strong>Riccardo Maranzana<\/strong><span class=\"apple-converted-space\">\u00a0<\/span>recita nel bosco dei Corbezzoli, accanto al quale \u00e8 inserita anche l\u2019interpretazione di<span class=\"apple-converted-space\">\u00a0<\/span><strong>Maria Grazia Plos<\/strong>, vicino ai crochi fioriti.<span class=\"apple-converted-space\">\u00a0<\/span><strong>Filippo Borghi<\/strong><span class=\"apple-converted-space\">\u00a0<\/span>chiude il canto nella galleria delle Camelie. L\u2019introduzione al XXXI canto, curata dal professor Fabio Romanini, \u00e8 videoregistrata nel Giardino all\u2019Italiana. Il XXXIII canto \u00e8 l\u2019ascesa verso il cielo e dunque \u00e8 ambientata in Castello: tutti gli attori della compagnia, prima di rientrare sotto le stelle del Teatro Rossetti, recitano alternandosi nella torretta del Castello.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Il 25 marzo celebriamo il\u00a0Danted\u00ec,\u00a0abbracciando e facendo risuonare dai luoghi di Miramare la bellezza universale delle parole del Sommo Poeta. Nella giornata che gli studiosi riconoscono come inizio del viaggio nell\u2019aldil\u00e0 della Divina Commedia, verr\u00e0 lanciato il video\u00a0\u201cVien dietro a me&#8230; Viaggio nella Divina Commedia attraverso i luoghi di Trieste\u201d. La trascendenza del Paradiso [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":8384,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[82,85,17],"tags":[],"class_list":["post-9275","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi-de","category-news-de","category-unkategorisiert"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Miramare, paradiso dantesco | Museo Storico e Parco del Castello di Miramare<\/title>\n<meta name=\"description\" content=\"Miramare, paradiso dantesco | Museo Storico e Parco del Castello di Miramare | Un luogo nobile e romatico tra arte, natura e bellezza. | &nbsp; Il 25 marzo celebriamo il\u00a0Danted\u00ec,\u00a0abbracciando e facendo risuonare dai luoghi di Miramare la bellezza universale delle parole del Sommo Poeta.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/miramare.cultura.gov.it\/de\/miramare-paradiso-dantesco-2\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Miramare, paradiso dantesco | Museo Storico e Parco del Castello di Miramare\" \/>\n<meta property=\"og:description\" content=\"Miramare, paradiso dantesco | Museo Storico e Parco del Castello di Miramare | Un luogo nobile e romatico tra arte, natura e bellezza. | &nbsp; Il 25 marzo celebriamo il\u00a0Danted\u00ec,\u00a0abbracciando e facendo risuonare dai luoghi di Miramare la bellezza universale delle parole del Sommo Poeta.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/miramare.cultura.gov.it\/de\/miramare-paradiso-dantesco-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Museo Storico e Parco del Castello di Miramare\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-28T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-10T10:04:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/miramare.cultura.gov.it\/wp-content\/uploads\/2022\/10\/SAVE_20210324_142253.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Amministratore Nethics\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Amministratore Nethics\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/de\\\/miramare-paradiso-dantesco-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/de\\\/miramare-paradiso-dantesco-2\\\/\"},\"author\":{\"name\":\"Amministratore Nethics\",\"@id\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/#\\\/schema\\\/person\\\/33d951967b8397a9d6cf883dc441b332\"},\"headline\":\"Miramare, paradiso dantesco\",\"datePublished\":\"2021-03-28T22:00:00+00:00\",\"dateModified\":\"2022-10-10T10:04:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/de\\\/miramare-paradiso-dantesco-2\\\/\"},\"wordCount\":263,\"image\":{\"@id\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/de\\\/miramare-paradiso-dantesco-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/SAVE_20210324_142253.jpg\",\"articleSection\":[\"Eventi\",\"News\",\"Unkategorisiert\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/de\\\/miramare-paradiso-dantesco-2\\\/\",\"url\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/de\\\/miramare-paradiso-dantesco-2\\\/\",\"name\":\"Miramare, paradiso dantesco | Museo Storico e Parco del Castello di Miramare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/de\\\/miramare-paradiso-dantesco-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/de\\\/miramare-paradiso-dantesco-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/SAVE_20210324_142253.jpg\",\"datePublished\":\"2021-03-28T22:00:00+00:00\",\"dateModified\":\"2022-10-10T10:04:29+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/#\\\/schema\\\/person\\\/33d951967b8397a9d6cf883dc441b332\"},\"description\":\"Miramare, paradiso dantesco | Museo Storico e Parco del Castello di Miramare | Un luogo nobile e romatico tra arte, natura e bellezza. | &nbsp; Il 25 marzo celebriamo il\u00a0Danted\u00ec,\u00a0abbracciando e facendo risuonare dai luoghi di Miramare la bellezza universale delle parole del Sommo Poeta.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/de\\\/miramare-paradiso-dantesco-2\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/miramare.cultura.gov.it\\\/de\\\/miramare-paradiso-dantesco-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/de\\\/miramare-paradiso-dantesco-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/SAVE_20210324_142253.jpg\",\"contentUrl\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/SAVE_20210324_142253.jpg\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/de\\\/miramare-paradiso-dantesco-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Miramare, paradiso dantesco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/#website\",\"url\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/\",\"name\":\"Museo Storico e Parco del Castello di Miramare\",\"description\":\"Un luogo nobile e romatico tra arte, natura e bellezza.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/#\\\/schema\\\/person\\\/33d951967b8397a9d6cf883dc441b332\",\"name\":\"Amministratore Nethics\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1193094f9692945935139e2fd8f07407468bb11639ae82b599eb810e25e9b106?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1193094f9692945935139e2fd8f07407468bb11639ae82b599eb810e25e9b106?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1193094f9692945935139e2fd8f07407468bb11639ae82b599eb810e25e9b106?s=96&d=mm&r=g\",\"caption\":\"Amministratore Nethics\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Miramare, paradiso dantesco | Museo Storico e Parco del Castello di Miramare","description":"Miramare, paradiso dantesco | Museo Storico e Parco del Castello di Miramare | Un luogo nobile e romatico tra arte, natura e bellezza. | &nbsp; Il 25 marzo celebriamo il\u00a0Danted\u00ec,\u00a0abbracciando e facendo risuonare dai luoghi di Miramare la bellezza universale delle parole del Sommo Poeta.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/miramare.cultura.gov.it\/de\/miramare-paradiso-dantesco-2\/","og_locale":"de_DE","og_type":"article","og_title":"Miramare, paradiso dantesco | Museo Storico e Parco del Castello di Miramare","og_description":"Miramare, paradiso dantesco | Museo Storico e Parco del Castello di Miramare | Un luogo nobile e romatico tra arte, natura e bellezza. | &nbsp; Il 25 marzo celebriamo il\u00a0Danted\u00ec,\u00a0abbracciando e facendo risuonare dai luoghi di Miramare la bellezza universale delle parole del Sommo Poeta.","og_url":"https:\/\/miramare.cultura.gov.it\/de\/miramare-paradiso-dantesco-2\/","og_site_name":"Museo Storico e Parco del Castello di Miramare","article_published_time":"2021-03-28T22:00:00+00:00","article_modified_time":"2022-10-10T10:04:29+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/miramare.cultura.gov.it\/wp-content\/uploads\/2022\/10\/SAVE_20210324_142253.jpg","type":"image\/jpeg"}],"author":"Amministratore Nethics","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Amministratore Nethics","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/miramare.cultura.gov.it\/de\/miramare-paradiso-dantesco-2\/#article","isPartOf":{"@id":"https:\/\/miramare.cultura.gov.it\/de\/miramare-paradiso-dantesco-2\/"},"author":{"name":"Amministratore Nethics","@id":"https:\/\/miramare.cultura.gov.it\/#\/schema\/person\/33d951967b8397a9d6cf883dc441b332"},"headline":"Miramare, paradiso dantesco","datePublished":"2021-03-28T22:00:00+00:00","dateModified":"2022-10-10T10:04:29+00:00","mainEntityOfPage":{"@id":"https:\/\/miramare.cultura.gov.it\/de\/miramare-paradiso-dantesco-2\/"},"wordCount":263,"image":{"@id":"https:\/\/miramare.cultura.gov.it\/de\/miramare-paradiso-dantesco-2\/#primaryimage"},"thumbnailUrl":"https:\/\/miramare.cultura.gov.it\/wp-content\/uploads\/2022\/10\/SAVE_20210324_142253.jpg","articleSection":["Eventi","News","Unkategorisiert"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/miramare.cultura.gov.it\/de\/miramare-paradiso-dantesco-2\/","url":"https:\/\/miramare.cultura.gov.it\/de\/miramare-paradiso-dantesco-2\/","name":"Miramare, paradiso dantesco | Museo Storico e Parco del Castello di Miramare","isPartOf":{"@id":"https:\/\/miramare.cultura.gov.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/miramare.cultura.gov.it\/de\/miramare-paradiso-dantesco-2\/#primaryimage"},"image":{"@id":"https:\/\/miramare.cultura.gov.it\/de\/miramare-paradiso-dantesco-2\/#primaryimage"},"thumbnailUrl":"https:\/\/miramare.cultura.gov.it\/wp-content\/uploads\/2022\/10\/SAVE_20210324_142253.jpg","datePublished":"2021-03-28T22:00:00+00:00","dateModified":"2022-10-10T10:04:29+00:00","author":{"@id":"https:\/\/miramare.cultura.gov.it\/#\/schema\/person\/33d951967b8397a9d6cf883dc441b332"},"description":"Miramare, paradiso dantesco | Museo Storico e Parco del Castello di Miramare | Un luogo nobile e romatico tra arte, natura e bellezza. | &nbsp; Il 25 marzo celebriamo il\u00a0Danted\u00ec,\u00a0abbracciando e facendo risuonare dai luoghi di Miramare la bellezza universale delle parole del Sommo Poeta.","breadcrumb":{"@id":"https:\/\/miramare.cultura.gov.it\/de\/miramare-paradiso-dantesco-2\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/miramare.cultura.gov.it\/de\/miramare-paradiso-dantesco-2\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/miramare.cultura.gov.it\/de\/miramare-paradiso-dantesco-2\/#primaryimage","url":"https:\/\/miramare.cultura.gov.it\/wp-content\/uploads\/2022\/10\/SAVE_20210324_142253.jpg","contentUrl":"https:\/\/miramare.cultura.gov.it\/wp-content\/uploads\/2022\/10\/SAVE_20210324_142253.jpg","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/miramare.cultura.gov.it\/de\/miramare-paradiso-dantesco-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/miramare.cultura.gov.it\/de\/"},{"@type":"ListItem","position":2,"name":"Miramare, paradiso dantesco"}]},{"@type":"WebSite","@id":"https:\/\/miramare.cultura.gov.it\/#website","url":"https:\/\/miramare.cultura.gov.it\/","name":"Museo Storico e Parco del Castello di Miramare","description":"Un luogo nobile e romatico tra arte, natura e bellezza.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/miramare.cultura.gov.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/miramare.cultura.gov.it\/#\/schema\/person\/33d951967b8397a9d6cf883dc441b332","name":"Amministratore Nethics","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/1193094f9692945935139e2fd8f07407468bb11639ae82b599eb810e25e9b106?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1193094f9692945935139e2fd8f07407468bb11639ae82b599eb810e25e9b106?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1193094f9692945935139e2fd8f07407468bb11639ae82b599eb810e25e9b106?s=96&d=mm&r=g","caption":"Amministratore Nethics"}}]}},"_links":{"self":[{"href":"https:\/\/miramare.cultura.gov.it\/de\/wp-json\/wp\/v2\/posts\/9275","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/miramare.cultura.gov.it\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/miramare.cultura.gov.it\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/miramare.cultura.gov.it\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/miramare.cultura.gov.it\/de\/wp-json\/wp\/v2\/comments?post=9275"}],"version-history":[{"count":1,"href":"https:\/\/miramare.cultura.gov.it\/de\/wp-json\/wp\/v2\/posts\/9275\/revisions"}],"predecessor-version":[{"id":9838,"href":"https:\/\/miramare.cultura.gov.it\/de\/wp-json\/wp\/v2\/posts\/9275\/revisions\/9838"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/miramare.cultura.gov.it\/de\/wp-json\/wp\/v2\/media\/8384"}],"wp:attachment":[{"href":"https:\/\/miramare.cultura.gov.it\/de\/wp-json\/wp\/v2\/media?parent=9275"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/miramare.cultura.gov.it\/de\/wp-json\/wp\/v2\/categories?post=9275"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/miramare.cultura.gov.it\/de\/wp-json\/wp\/v2\/tags?post=9275"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}