{"id":9147,"date":"2021-03-06T00:00:00","date_gmt":"2021-03-05T23:00:00","guid":{"rendered":"https:\/\/miramare.cultura.gov.it\/avviso-sospensione-dei-servizi-di-apertura-al-pubblico-dall-8-marzo-2021\/"},"modified":"2022-10-10T12:16:19","modified_gmt":"2022-10-10T10:16:19","slug":"avviso-sospensione-dei-servizi-di-apertura-al-pubblico-dall-8-marzo-2021","status":"publish","type":"post","link":"https:\/\/miramare.cultura.gov.it\/en\/avviso-sospensione-dei-servizi-di-apertura-al-pubblico-dall-8-marzo-2021\/","title":{"rendered":"AVVISO \u2013 SOSPENSIONE DEI SERVIZI DI APERTURA AL PUBBLICO DALL&#8217; 8 MARZO 2021"},"content":{"rendered":"<p>La regione <strong>Friuli Venezia Giulia<\/strong> \u00e8 tornata in <strong>zona arancione<\/strong>.<br \/>\nPertanto, in linea con le direttive governative mirate al contrasto e al contenimento del diffondersi del virus COVID-19, da<strong> luned\u00ec 8 marzo verr\u00e0 sospeso il servizio di apertura al pubblico del Castello.<\/strong><\/p>\n<p>La sospensione rester\u00e0 in vigore fino a quando la nostra regione non rientrer\u00e0 in zona gialla.<\/p>\n<p>Salvo nuove disposizioni, al momento <strong>rimane <\/strong>invece<strong> aperto<\/strong> al pubblico il <strong>Parco<\/strong> che osserver\u00e0 i consueti orari del periodo: marzo, <strong>tutti i giorni, dalle 8 alle 18.<\/strong><\/p>\n<p>Seguiteci sui nostri canali social (@museomiramare) perch\u00e9 continueremo a raccontarvi la Collezione del Museo e condividere con voi la bellezza di questo luogo che amiamo tutti cos\u00ec tanto.<\/p>\n<p>Arrivederci a presto!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La regione Friuli Venezia Giulia \u00e8 tornata in zona arancione. Pertanto, in linea con le direttive governative mirate al contrasto e al contenimento del diffondersi del virus COVID-19, da luned\u00ec 8 marzo verr\u00e0 sospeso il servizio di apertura al pubblico del Castello. La sospensione rester\u00e0 in vigore fino a quando la nostra regione non rientrer\u00e0 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":8362,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[76],"tags":[],"class_list":["post-9147","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-en"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AVVISO \u2013 SOSPENSIONE DEI SERVIZI DI APERTURA AL PUBBLICO DALL&#039; 8 MARZO 2021 | Museo Storico e Parco del Castello di Miramare<\/title>\n<meta name=\"description\" content=\"AVVISO \u2013 SOSPENSIONE DEI SERVIZI DI APERTURA AL PUBBLICO DALL&#039; 8 MARZO 2021 | Museo Storico e Parco del Castello di Miramare | Un luogo nobile e romatico tra arte, natura e bellezza. | La regione Friuli Venezia Giulia \u00e8 tornata in zona arancione. Pertanto, in linea con le direttive governative mirate al contrasto e al contenimento del\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/miramare.cultura.gov.it\/en\/avviso-sospensione-dei-servizi-di-apertura-al-pubblico-dall-8-marzo-2021\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AVVISO \u2013 SOSPENSIONE DEI SERVIZI DI APERTURA AL PUBBLICO DALL&#039; 8 MARZO 2021 | Museo Storico e Parco del Castello di Miramare\" \/>\n<meta property=\"og:description\" content=\"AVVISO \u2013 SOSPENSIONE DEI SERVIZI DI APERTURA AL PUBBLICO DALL&#039; 8 MARZO 2021 | Museo Storico e Parco del Castello di Miramare | Un luogo nobile e romatico tra arte, natura e bellezza. | La regione Friuli Venezia Giulia \u00e8 tornata in zona arancione. Pertanto, in linea con le direttive governative mirate al contrasto e al contenimento del\" \/>\n<meta property=\"og:url\" content=\"https:\/\/miramare.cultura.gov.it\/en\/avviso-sospensione-dei-servizi-di-apertura-al-pubblico-dall-8-marzo-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"Museo Storico e Parco del Castello di Miramare\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-05T23:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-10T10:16:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/miramare.cultura.gov.it\/wp-content\/uploads\/2022\/10\/COMUNICAZIONI-IMPORTANTI.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Amministratore Nethics\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Amministratore Nethics\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/en\\\/avviso-sospensione-dei-servizi-di-apertura-al-pubblico-dall-8-marzo-2021\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/en\\\/avviso-sospensione-dei-servizi-di-apertura-al-pubblico-dall-8-marzo-2021\\\/\"},\"author\":{\"name\":\"Amministratore Nethics\",\"@id\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/#\\\/schema\\\/person\\\/33d951967b8397a9d6cf883dc441b332\"},\"headline\":\"AVVISO \u2013 SOSPENSIONE DEI SERVIZI DI APERTURA AL PUBBLICO DALL&#8217; 8 MARZO 2021\",\"datePublished\":\"2021-03-05T23:00:00+00:00\",\"dateModified\":\"2022-10-10T10:16:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/en\\\/avviso-sospensione-dei-servizi-di-apertura-al-pubblico-dall-8-marzo-2021\\\/\"},\"wordCount\":122,\"image\":{\"@id\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/en\\\/avviso-sospensione-dei-servizi-di-apertura-al-pubblico-dall-8-marzo-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/COMUNICAZIONI-IMPORTANTI.png\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/en\\\/avviso-sospensione-dei-servizi-di-apertura-al-pubblico-dall-8-marzo-2021\\\/\",\"url\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/en\\\/avviso-sospensione-dei-servizi-di-apertura-al-pubblico-dall-8-marzo-2021\\\/\",\"name\":\"AVVISO \u2013 SOSPENSIONE DEI SERVIZI DI APERTURA AL PUBBLICO DALL' 8 MARZO 2021 | Museo Storico e Parco del Castello di Miramare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/en\\\/avviso-sospensione-dei-servizi-di-apertura-al-pubblico-dall-8-marzo-2021\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/en\\\/avviso-sospensione-dei-servizi-di-apertura-al-pubblico-dall-8-marzo-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/COMUNICAZIONI-IMPORTANTI.png\",\"datePublished\":\"2021-03-05T23:00:00+00:00\",\"dateModified\":\"2022-10-10T10:16:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/#\\\/schema\\\/person\\\/33d951967b8397a9d6cf883dc441b332\"},\"description\":\"AVVISO \u2013 SOSPENSIONE DEI SERVIZI DI APERTURA AL PUBBLICO DALL' 8 MARZO 2021 | Museo Storico e Parco del Castello di Miramare | Un luogo nobile e romatico tra arte, natura e bellezza. | La regione Friuli Venezia Giulia \u00e8 tornata in zona arancione. Pertanto, in linea con le direttive governative mirate al contrasto e al contenimento del\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/en\\\/avviso-sospensione-dei-servizi-di-apertura-al-pubblico-dall-8-marzo-2021\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/miramare.cultura.gov.it\\\/en\\\/avviso-sospensione-dei-servizi-di-apertura-al-pubblico-dall-8-marzo-2021\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/en\\\/avviso-sospensione-dei-servizi-di-apertura-al-pubblico-dall-8-marzo-2021\\\/#primaryimage\",\"url\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/COMUNICAZIONI-IMPORTANTI.png\",\"contentUrl\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/COMUNICAZIONI-IMPORTANTI.png\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/en\\\/avviso-sospensione-dei-servizi-di-apertura-al-pubblico-dall-8-marzo-2021\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AVVISO \u2013 SOSPENSIONE DEI SERVIZI DI APERTURA AL PUBBLICO DALL&#8217; 8 MARZO 2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/#website\",\"url\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/\",\"name\":\"Museo Storico e Parco del Castello di Miramare\",\"description\":\"Un luogo nobile e romatico tra arte, natura e bellezza.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/#\\\/schema\\\/person\\\/33d951967b8397a9d6cf883dc441b332\",\"name\":\"Amministratore Nethics\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1193094f9692945935139e2fd8f07407468bb11639ae82b599eb810e25e9b106?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1193094f9692945935139e2fd8f07407468bb11639ae82b599eb810e25e9b106?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1193094f9692945935139e2fd8f07407468bb11639ae82b599eb810e25e9b106?s=96&d=mm&r=g\",\"caption\":\"Amministratore Nethics\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AVVISO \u2013 SOSPENSIONE DEI SERVIZI DI APERTURA AL PUBBLICO DALL' 8 MARZO 2021 | Museo Storico e Parco del Castello di Miramare","description":"AVVISO \u2013 SOSPENSIONE DEI SERVIZI DI APERTURA AL PUBBLICO DALL' 8 MARZO 2021 | Museo Storico e Parco del Castello di Miramare | Un luogo nobile e romatico tra arte, natura e bellezza. | La regione Friuli Venezia Giulia \u00e8 tornata in zona arancione. Pertanto, in linea con le direttive governative mirate al contrasto e al contenimento del","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/miramare.cultura.gov.it\/en\/avviso-sospensione-dei-servizi-di-apertura-al-pubblico-dall-8-marzo-2021\/","og_locale":"en_US","og_type":"article","og_title":"AVVISO \u2013 SOSPENSIONE DEI SERVIZI DI APERTURA AL PUBBLICO DALL' 8 MARZO 2021 | Museo Storico e Parco del Castello di Miramare","og_description":"AVVISO \u2013 SOSPENSIONE DEI SERVIZI DI APERTURA AL PUBBLICO DALL' 8 MARZO 2021 | Museo Storico e Parco del Castello di Miramare | Un luogo nobile e romatico tra arte, natura e bellezza. | La regione Friuli Venezia Giulia \u00e8 tornata in zona arancione. Pertanto, in linea con le direttive governative mirate al contrasto e al contenimento del","og_url":"https:\/\/miramare.cultura.gov.it\/en\/avviso-sospensione-dei-servizi-di-apertura-al-pubblico-dall-8-marzo-2021\/","og_site_name":"Museo Storico e Parco del Castello di Miramare","article_published_time":"2021-03-05T23:00:00+00:00","article_modified_time":"2022-10-10T10:16:19+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/miramare.cultura.gov.it\/wp-content\/uploads\/2022\/10\/COMUNICAZIONI-IMPORTANTI.png","type":"image\/png"}],"author":"Amministratore Nethics","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Amministratore Nethics","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/miramare.cultura.gov.it\/en\/avviso-sospensione-dei-servizi-di-apertura-al-pubblico-dall-8-marzo-2021\/#article","isPartOf":{"@id":"https:\/\/miramare.cultura.gov.it\/en\/avviso-sospensione-dei-servizi-di-apertura-al-pubblico-dall-8-marzo-2021\/"},"author":{"name":"Amministratore Nethics","@id":"https:\/\/miramare.cultura.gov.it\/#\/schema\/person\/33d951967b8397a9d6cf883dc441b332"},"headline":"AVVISO \u2013 SOSPENSIONE DEI SERVIZI DI APERTURA AL PUBBLICO DALL&#8217; 8 MARZO 2021","datePublished":"2021-03-05T23:00:00+00:00","dateModified":"2022-10-10T10:16:19+00:00","mainEntityOfPage":{"@id":"https:\/\/miramare.cultura.gov.it\/en\/avviso-sospensione-dei-servizi-di-apertura-al-pubblico-dall-8-marzo-2021\/"},"wordCount":122,"image":{"@id":"https:\/\/miramare.cultura.gov.it\/en\/avviso-sospensione-dei-servizi-di-apertura-al-pubblico-dall-8-marzo-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/miramare.cultura.gov.it\/wp-content\/uploads\/2022\/10\/COMUNICAZIONI-IMPORTANTI.png","articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/miramare.cultura.gov.it\/en\/avviso-sospensione-dei-servizi-di-apertura-al-pubblico-dall-8-marzo-2021\/","url":"https:\/\/miramare.cultura.gov.it\/en\/avviso-sospensione-dei-servizi-di-apertura-al-pubblico-dall-8-marzo-2021\/","name":"AVVISO \u2013 SOSPENSIONE DEI SERVIZI DI APERTURA AL PUBBLICO DALL' 8 MARZO 2021 | Museo Storico e Parco del Castello di Miramare","isPartOf":{"@id":"https:\/\/miramare.cultura.gov.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/miramare.cultura.gov.it\/en\/avviso-sospensione-dei-servizi-di-apertura-al-pubblico-dall-8-marzo-2021\/#primaryimage"},"image":{"@id":"https:\/\/miramare.cultura.gov.it\/en\/avviso-sospensione-dei-servizi-di-apertura-al-pubblico-dall-8-marzo-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/miramare.cultura.gov.it\/wp-content\/uploads\/2022\/10\/COMUNICAZIONI-IMPORTANTI.png","datePublished":"2021-03-05T23:00:00+00:00","dateModified":"2022-10-10T10:16:19+00:00","author":{"@id":"https:\/\/miramare.cultura.gov.it\/#\/schema\/person\/33d951967b8397a9d6cf883dc441b332"},"description":"AVVISO \u2013 SOSPENSIONE DEI SERVIZI DI APERTURA AL PUBBLICO DALL' 8 MARZO 2021 | Museo Storico e Parco del Castello di Miramare | Un luogo nobile e romatico tra arte, natura e bellezza. | La regione Friuli Venezia Giulia \u00e8 tornata in zona arancione. Pertanto, in linea con le direttive governative mirate al contrasto e al contenimento del","breadcrumb":{"@id":"https:\/\/miramare.cultura.gov.it\/en\/avviso-sospensione-dei-servizi-di-apertura-al-pubblico-dall-8-marzo-2021\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/miramare.cultura.gov.it\/en\/avviso-sospensione-dei-servizi-di-apertura-al-pubblico-dall-8-marzo-2021\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/miramare.cultura.gov.it\/en\/avviso-sospensione-dei-servizi-di-apertura-al-pubblico-dall-8-marzo-2021\/#primaryimage","url":"https:\/\/miramare.cultura.gov.it\/wp-content\/uploads\/2022\/10\/COMUNICAZIONI-IMPORTANTI.png","contentUrl":"https:\/\/miramare.cultura.gov.it\/wp-content\/uploads\/2022\/10\/COMUNICAZIONI-IMPORTANTI.png","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/miramare.cultura.gov.it\/en\/avviso-sospensione-dei-servizi-di-apertura-al-pubblico-dall-8-marzo-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/miramare.cultura.gov.it\/en\/"},{"@type":"ListItem","position":2,"name":"AVVISO \u2013 SOSPENSIONE DEI SERVIZI DI APERTURA AL PUBBLICO DALL&#8217; 8 MARZO 2021"}]},{"@type":"WebSite","@id":"https:\/\/miramare.cultura.gov.it\/#website","url":"https:\/\/miramare.cultura.gov.it\/","name":"Museo Storico e Parco del Castello di Miramare","description":"Un luogo nobile e romatico tra arte, natura e bellezza.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/miramare.cultura.gov.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/miramare.cultura.gov.it\/#\/schema\/person\/33d951967b8397a9d6cf883dc441b332","name":"Amministratore Nethics","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/1193094f9692945935139e2fd8f07407468bb11639ae82b599eb810e25e9b106?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1193094f9692945935139e2fd8f07407468bb11639ae82b599eb810e25e9b106?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1193094f9692945935139e2fd8f07407468bb11639ae82b599eb810e25e9b106?s=96&d=mm&r=g","caption":"Amministratore Nethics"}}]}},"_links":{"self":[{"href":"https:\/\/miramare.cultura.gov.it\/en\/wp-json\/wp\/v2\/posts\/9147","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/miramare.cultura.gov.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/miramare.cultura.gov.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/miramare.cultura.gov.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/miramare.cultura.gov.it\/en\/wp-json\/wp\/v2\/comments?post=9147"}],"version-history":[{"count":1,"href":"https:\/\/miramare.cultura.gov.it\/en\/wp-json\/wp\/v2\/posts\/9147\/revisions"}],"predecessor-version":[{"id":9875,"href":"https:\/\/miramare.cultura.gov.it\/en\/wp-json\/wp\/v2\/posts\/9147\/revisions\/9875"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/miramare.cultura.gov.it\/en\/wp-json\/wp\/v2\/media\/8362"}],"wp:attachment":[{"href":"https:\/\/miramare.cultura.gov.it\/en\/wp-json\/wp\/v2\/media?parent=9147"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/miramare.cultura.gov.it\/en\/wp-json\/wp\/v2\/categories?post=9147"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/miramare.cultura.gov.it\/en\/wp-json\/wp\/v2\/tags?post=9147"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}