{"id":9161,"date":"2021-04-26T00:00:00","date_gmt":"2021-04-25T22:00:00","guid":{"rendered":"https:\/\/miramare.cultura.gov.it\/la-giornata-europea-dei-giardini-storici\/"},"modified":"2022-10-10T12:00:21","modified_gmt":"2022-10-10T10:00:21","slug":"la-giornata-europea-dei-giardini-storici","status":"publish","type":"post","link":"https:\/\/miramare.cultura.gov.it\/en\/la-giornata-europea-dei-giardini-storici\/","title":{"rendered":"La Giornata Europea dei Giardini Storici"},"content":{"rendered":"<p><iframe loading=\"lazy\" title=\"European aesthetic styles at Miramare Park\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/oC4RUBirmGQ?feature=oembed\"  allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p>Miramare omaggia la seconda Giornata Europea dei Giardini Storici con un video che volteggia sul Parco di Miramare.<\/p>\n<p>Nato per essere\u00a0una stazione sperimentale di rimboschimento e di acclimatazione di specie botaniche rare, il Parco \u00e8 una commistione di diversi concetti di giardino e di stili legati all\u2019epoca di Massimiliano che l\u2019attuale direzione sta recuperando in modo filologico sulla base di documenti storici, carteggi e foto dell\u2019epoca.\u00a0Questo luogo \u00e8 di certo legato all\u2019eclettismo dell\u2019Ottocento, ma la sua vera unicit\u00e0 risiede nella passione per la sperimentazione e per la botanica del suo ideatore. Oggi, questa straordinaria capacit\u00e0 di riconoscere i diversi volti della bellezza, di accostarli e farli dialogare tra loro rende il Parco di Miramare un perfetto punto d&#8217;incontro per la crescita dell&#8217;identit\u00e0 europea.<\/p>\n<p>Tutte le iniziative del II EDHG (26.04.2021):\u00a0<a href=\"https:\/\/europeanhistoricgardens.eu\/en\/european-day-historic-gardens\/\">https:\/\/europeanhistoricgardens.eu\/en\/european-day-historic-gardens\/<\/a><\/p>\n<p>#EuropeanDayHistoricGardens<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Miramare omaggia la seconda Giornata Europea dei Giardini Storici con un video che volteggia sul Parco di Miramare. Nato per essere\u00a0una stazione sperimentale di rimboschimento e di acclimatazione di specie botaniche rare, il Parco \u00e8 una commistione di diversi concetti di giardino e di stili legati all\u2019epoca di Massimiliano che l\u2019attuale direzione sta recuperando [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":8436,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[74,76],"tags":[],"class_list":["post-9161","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-media-en","category-news-en"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Giornata Europea dei Giardini Storici | Museo Storico e Parco del Castello di Miramare<\/title>\n<meta name=\"description\" content=\"La Giornata Europea dei Giardini Storici | Museo Storico e Parco del Castello di Miramare | Un luogo nobile e romatico tra arte, natura e bellezza. | &nbsp; Miramare omaggia la seconda Giornata Europea dei Giardini Storici con un video che volteggia sul Parco di Miramare. Nato per essere\u00a0una stazione\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/miramare.cultura.gov.it\/en\/la-giornata-europea-dei-giardini-storici\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Giornata Europea dei Giardini Storici | Museo Storico e Parco del Castello di Miramare\" \/>\n<meta property=\"og:description\" content=\"La Giornata Europea dei Giardini Storici | Museo Storico e Parco del Castello di Miramare | Un luogo nobile e romatico tra arte, natura e bellezza. | &nbsp; Miramare omaggia la seconda Giornata Europea dei Giardini Storici con un video che volteggia sul Parco di Miramare. Nato per essere\u00a0una stazione\" \/>\n<meta property=\"og:url\" content=\"https:\/\/miramare.cultura.gov.it\/en\/la-giornata-europea-dei-giardini-storici\/\" \/>\n<meta property=\"og:site_name\" content=\"Museo Storico e Parco del Castello di Miramare\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-25T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-10T10:00:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/miramare.cultura.gov.it\/wp-content\/uploads\/2022\/10\/screenMiramare.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1267\" \/>\n\t<meta property=\"og:image:height\" content=\"721\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Amministratore Nethics\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Amministratore Nethics\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/en\\\/la-giornata-europea-dei-giardini-storici\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/en\\\/la-giornata-europea-dei-giardini-storici\\\/\"},\"author\":{\"name\":\"Amministratore Nethics\",\"@id\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/#\\\/schema\\\/person\\\/33d951967b8397a9d6cf883dc441b332\"},\"headline\":\"La Giornata Europea dei Giardini Storici\",\"datePublished\":\"2021-04-25T22:00:00+00:00\",\"dateModified\":\"2022-10-10T10:00:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/en\\\/la-giornata-europea-dei-giardini-storici\\\/\"},\"wordCount\":154,\"image\":{\"@id\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/en\\\/la-giornata-europea-dei-giardini-storici\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/screenMiramare.jpg\",\"articleSection\":[\"Media\",\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/en\\\/la-giornata-europea-dei-giardini-storici\\\/\",\"url\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/en\\\/la-giornata-europea-dei-giardini-storici\\\/\",\"name\":\"La Giornata Europea dei Giardini Storici | Museo Storico e Parco del Castello di Miramare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/en\\\/la-giornata-europea-dei-giardini-storici\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/en\\\/la-giornata-europea-dei-giardini-storici\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/screenMiramare.jpg\",\"datePublished\":\"2021-04-25T22:00:00+00:00\",\"dateModified\":\"2022-10-10T10:00:21+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/#\\\/schema\\\/person\\\/33d951967b8397a9d6cf883dc441b332\"},\"description\":\"La Giornata Europea dei Giardini Storici | Museo Storico e Parco del Castello di Miramare | Un luogo nobile e romatico tra arte, natura e bellezza. | &nbsp; Miramare omaggia la seconda Giornata Europea dei Giardini Storici con un video che volteggia sul Parco di Miramare. Nato per essere\u00a0una stazione\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/en\\\/la-giornata-europea-dei-giardini-storici\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/miramare.cultura.gov.it\\\/en\\\/la-giornata-europea-dei-giardini-storici\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/en\\\/la-giornata-europea-dei-giardini-storici\\\/#primaryimage\",\"url\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/screenMiramare.jpg\",\"contentUrl\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/screenMiramare.jpg\",\"width\":1267,\"height\":721},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/en\\\/la-giornata-europea-dei-giardini-storici\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Giornata Europea dei Giardini Storici\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/#website\",\"url\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/\",\"name\":\"Museo Storico e Parco del Castello di Miramare\",\"description\":\"Un luogo nobile e romatico tra arte, natura e bellezza.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/miramare.cultura.gov.it\\\/#\\\/schema\\\/person\\\/33d951967b8397a9d6cf883dc441b332\",\"name\":\"Amministratore Nethics\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1193094f9692945935139e2fd8f07407468bb11639ae82b599eb810e25e9b106?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1193094f9692945935139e2fd8f07407468bb11639ae82b599eb810e25e9b106?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1193094f9692945935139e2fd8f07407468bb11639ae82b599eb810e25e9b106?s=96&d=mm&r=g\",\"caption\":\"Amministratore Nethics\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Giornata Europea dei Giardini Storici | Museo Storico e Parco del Castello di Miramare","description":"La Giornata Europea dei Giardini Storici | Museo Storico e Parco del Castello di Miramare | Un luogo nobile e romatico tra arte, natura e bellezza. | &nbsp; Miramare omaggia la seconda Giornata Europea dei Giardini Storici con un video che volteggia sul Parco di Miramare. Nato per essere\u00a0una stazione","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/miramare.cultura.gov.it\/en\/la-giornata-europea-dei-giardini-storici\/","og_locale":"en_US","og_type":"article","og_title":"La Giornata Europea dei Giardini Storici | Museo Storico e Parco del Castello di Miramare","og_description":"La Giornata Europea dei Giardini Storici | Museo Storico e Parco del Castello di Miramare | Un luogo nobile e romatico tra arte, natura e bellezza. | &nbsp; Miramare omaggia la seconda Giornata Europea dei Giardini Storici con un video che volteggia sul Parco di Miramare. Nato per essere\u00a0una stazione","og_url":"https:\/\/miramare.cultura.gov.it\/en\/la-giornata-europea-dei-giardini-storici\/","og_site_name":"Museo Storico e Parco del Castello di Miramare","article_published_time":"2021-04-25T22:00:00+00:00","article_modified_time":"2022-10-10T10:00:21+00:00","og_image":[{"width":1267,"height":721,"url":"https:\/\/miramare.cultura.gov.it\/wp-content\/uploads\/2022\/10\/screenMiramare.jpg","type":"image\/jpeg"}],"author":"Amministratore Nethics","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Amministratore Nethics","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/miramare.cultura.gov.it\/en\/la-giornata-europea-dei-giardini-storici\/#article","isPartOf":{"@id":"https:\/\/miramare.cultura.gov.it\/en\/la-giornata-europea-dei-giardini-storici\/"},"author":{"name":"Amministratore Nethics","@id":"https:\/\/miramare.cultura.gov.it\/#\/schema\/person\/33d951967b8397a9d6cf883dc441b332"},"headline":"La Giornata Europea dei Giardini Storici","datePublished":"2021-04-25T22:00:00+00:00","dateModified":"2022-10-10T10:00:21+00:00","mainEntityOfPage":{"@id":"https:\/\/miramare.cultura.gov.it\/en\/la-giornata-europea-dei-giardini-storici\/"},"wordCount":154,"image":{"@id":"https:\/\/miramare.cultura.gov.it\/en\/la-giornata-europea-dei-giardini-storici\/#primaryimage"},"thumbnailUrl":"https:\/\/miramare.cultura.gov.it\/wp-content\/uploads\/2022\/10\/screenMiramare.jpg","articleSection":["Media","News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/miramare.cultura.gov.it\/en\/la-giornata-europea-dei-giardini-storici\/","url":"https:\/\/miramare.cultura.gov.it\/en\/la-giornata-europea-dei-giardini-storici\/","name":"La Giornata Europea dei Giardini Storici | Museo Storico e Parco del Castello di Miramare","isPartOf":{"@id":"https:\/\/miramare.cultura.gov.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/miramare.cultura.gov.it\/en\/la-giornata-europea-dei-giardini-storici\/#primaryimage"},"image":{"@id":"https:\/\/miramare.cultura.gov.it\/en\/la-giornata-europea-dei-giardini-storici\/#primaryimage"},"thumbnailUrl":"https:\/\/miramare.cultura.gov.it\/wp-content\/uploads\/2022\/10\/screenMiramare.jpg","datePublished":"2021-04-25T22:00:00+00:00","dateModified":"2022-10-10T10:00:21+00:00","author":{"@id":"https:\/\/miramare.cultura.gov.it\/#\/schema\/person\/33d951967b8397a9d6cf883dc441b332"},"description":"La Giornata Europea dei Giardini Storici | Museo Storico e Parco del Castello di Miramare | Un luogo nobile e romatico tra arte, natura e bellezza. | &nbsp; Miramare omaggia la seconda Giornata Europea dei Giardini Storici con un video che volteggia sul Parco di Miramare. Nato per essere\u00a0una stazione","breadcrumb":{"@id":"https:\/\/miramare.cultura.gov.it\/en\/la-giornata-europea-dei-giardini-storici\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/miramare.cultura.gov.it\/en\/la-giornata-europea-dei-giardini-storici\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/miramare.cultura.gov.it\/en\/la-giornata-europea-dei-giardini-storici\/#primaryimage","url":"https:\/\/miramare.cultura.gov.it\/wp-content\/uploads\/2022\/10\/screenMiramare.jpg","contentUrl":"https:\/\/miramare.cultura.gov.it\/wp-content\/uploads\/2022\/10\/screenMiramare.jpg","width":1267,"height":721},{"@type":"BreadcrumbList","@id":"https:\/\/miramare.cultura.gov.it\/en\/la-giornata-europea-dei-giardini-storici\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/miramare.cultura.gov.it\/en\/"},{"@type":"ListItem","position":2,"name":"La Giornata Europea dei Giardini Storici"}]},{"@type":"WebSite","@id":"https:\/\/miramare.cultura.gov.it\/#website","url":"https:\/\/miramare.cultura.gov.it\/","name":"Museo Storico e Parco del Castello di Miramare","description":"Un luogo nobile e romatico tra arte, natura e bellezza.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/miramare.cultura.gov.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/miramare.cultura.gov.it\/#\/schema\/person\/33d951967b8397a9d6cf883dc441b332","name":"Amministratore Nethics","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/1193094f9692945935139e2fd8f07407468bb11639ae82b599eb810e25e9b106?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1193094f9692945935139e2fd8f07407468bb11639ae82b599eb810e25e9b106?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1193094f9692945935139e2fd8f07407468bb11639ae82b599eb810e25e9b106?s=96&d=mm&r=g","caption":"Amministratore Nethics"}}]}},"_links":{"self":[{"href":"https:\/\/miramare.cultura.gov.it\/en\/wp-json\/wp\/v2\/posts\/9161","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/miramare.cultura.gov.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/miramare.cultura.gov.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/miramare.cultura.gov.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/miramare.cultura.gov.it\/en\/wp-json\/wp\/v2\/comments?post=9161"}],"version-history":[{"count":1,"href":"https:\/\/miramare.cultura.gov.it\/en\/wp-json\/wp\/v2\/posts\/9161\/revisions"}],"predecessor-version":[{"id":9813,"href":"https:\/\/miramare.cultura.gov.it\/en\/wp-json\/wp\/v2\/posts\/9161\/revisions\/9813"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/miramare.cultura.gov.it\/en\/wp-json\/wp\/v2\/media\/8436"}],"wp:attachment":[{"href":"https:\/\/miramare.cultura.gov.it\/en\/wp-json\/wp\/v2\/media?parent=9161"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/miramare.cultura.gov.it\/en\/wp-json\/wp\/v2\/categories?post=9161"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/miramare.cultura.gov.it\/en\/wp-json\/wp\/v2\/tags?post=9161"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}